{"id":9159,"date":"2022-05-18T10:14:38","date_gmt":"2022-05-18T13:14:38","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=9159"},"modified":"2022-05-18T10:14:40","modified_gmt":"2022-05-18T13:14:40","slug":"cadaver-e-encontrado-em-meio-a-mato-alto-no-bairro-maracana-em-foz","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2022\/05\/18\/cadaver-e-encontrado-em-meio-a-mato-alto-no-bairro-maracana-em-foz\/","title":{"rendered":"Cad\u00e1ver \u00e9 encontrado em meio a mato alto no bairro Maracan\u00e3 em Foz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">V\u00edtima foi identifica pela Pol\u00edcia Civil como: Silvano dos Santos Gon\u00e7alves de 41 anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na manh\u00e3 dessa ter\u00e7a-feira, 17, foi achado um cad\u00e1ver em meio ao mato alto na regi\u00e3o do bairro Maracan\u00e3, na Rua Mato Grosso esquina com a Avenida Felipe Wandscheer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No local estiveram reunidos a Pol\u00edcia Civil atrav\u00e9s da Delegacia de Homic\u00eddios, o Instituto M\u00e9dico Legal (IML), Pol\u00edcia Militar e Samu reunidos para identifica\u00e7\u00e3o da v\u00edtima e an\u00e1lise do caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a Pol\u00edcia Civil, o corpo \u00e9 de um homem de aproximadamente quarenta (40) anos que trajava cal\u00e7a jeans e camiseta de cor clara. Posteriormente a v\u00edtima foi identificada como Silvano dos Santos Gon\u00e7alves de 41 anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 o momento n\u00e3o h\u00e1 confirma\u00e7\u00e3o sobre a causa morte. A Pol\u00edcia aguarda o laudo do IML para confirmar se o caso pode se tratar de um homic\u00eddio ou n\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00edtima foi identifica pela Pol\u00edcia Civil como: Silvano dos Santos Gon\u00e7alves de 41 anos. Na manh\u00e3 dessa ter\u00e7a-feira, 17, foi achado um cad\u00e1ver em meio ao mato alto na regi\u00e3o do bairro Maracan\u00e3, na Rua Mato Grosso esquina com a Avenida Felipe Wandscheer. No local estiveram reunidos a Pol\u00edcia Civil atrav\u00e9s da Delegacia de Homic\u00eddios, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,20],"tags":[],"class_list":["post-9159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-seguranca"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9159"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9159\/revisions"}],"predecessor-version":[{"id":9161,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9159\/revisions\/9161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/9160"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}