{"id":9114,"date":"2022-05-16T15:35:27","date_gmt":"2022-05-16T18:35:27","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=9114"},"modified":"2022-05-16T15:35:29","modified_gmt":"2022-05-16T18:35:29","slug":"massa-de-ar-polar-vai-derrubar-as-temperaturas-no-parana","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2022\/05\/16\/massa-de-ar-polar-vai-derrubar-as-temperaturas-no-parana\/","title":{"rendered":"Massa de ar polar vai derrubar as temperaturas no Paran\u00e1"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A chegada de uma massa de ar polar vai derrubar as temperaturas no Paran\u00e1 a partir desta ter\u00e7a-feira <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A chegada de uma massa de ar polar vai derrubar as temperaturas no Paran\u00e1 a partir desta ter\u00e7a-feira (17), com expectativa de zero grau no extremo Sul do Estado. De acordo a com previs\u00e3o, o vento intenso dar\u00e1 a sensa\u00e7\u00e3o de temperaturas ainda mais baixas do que aquelas registradas nos term\u00f4metros. O Simepar \u2013 Sistema de Tecnologia e Monitoramento Ambiental do Paran\u00e1 alerta para a ocorr\u00eancia de geada, mas sem condi\u00e7\u00f5es favor\u00e1veis para a neve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesta segunda-feira (16), em Curitiba, a temperatura m\u00ednima registrada foi de 11\u00b0C no in\u00edcio do dia, mas a menor ocorrer\u00e1 \u00e0 noite, segundo o Simepar, situa\u00e7\u00e3o que se repetir\u00e1 em todas as regi\u00f5es paranaenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos pr\u00f3ximos dias, no Paran\u00e1, os term\u00f4metros chegam a 3\u00baC em muitos pontos do Estado, com sensa\u00e7\u00e3o t\u00e9rmica ainda mais baixa. \u201cNo Paran\u00e1, a tend\u00eancia \u00e9 de termos temperaturas mais baixas entre o Sul, Centro-Sul e o Leste do Estado, com temperaturas abaixo dos 5\u00b0C nos term\u00f4metros na divisa com Santa Catarina. Entre as cidades da regi\u00e3o, como Guarapuava, Palmas e General Carneiro, fica pr\u00f3xima a zero grau, com a sensa\u00e7\u00e3o de frio acentuada pelos ventos\u201d, detalha o meteorologista do Simepar Lizandro Jac\u00f3bsen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre a possibilidade de neve no Paran\u00e1, ele explica que os indicadores apontam para a ocorr\u00eancia de chuva congelada na divisa com Santa Catarina devido \u00e0 garoa. Embora sejam fen\u00f4menos bem pr\u00f3ximos, ela \u00e9 formada por um tipo de granizo bem pequeno, enquanto a neve chega em forma de flocos. \u201cA chuva congelada quica no para-brisa enquanto a neve gruda nele\u201d, simplifica Jac\u00f3bsen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao longo de ter\u00e7a, as nuvens perdem for\u00e7a, mas n\u00e3o esquenta. Na p\u00e1gina do&nbsp;<a href=\"http:\/\/www.simepar.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Simepar<\/a>, \u00e9 divulgada a previs\u00e3o para os pr\u00f3ximos 15 dias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>GEADAS&nbsp;<\/strong>\u2013 Previstas em v\u00e1rios pontos do Estado, as geadas ocorrem de intensidade fraca a moderada de acordo com a regi\u00e3o, exceto no Litoral. Com o fen\u00f4meno, na cafeicultura recomenda-se o enterrio de mudas. Hortali\u00e7as, leguminosas, \u00e1rvores frut\u00edferas tropicais rec\u00e9m-plantadas e demais culturas sens\u00edveis devem ser protegidas com aquecimento, irriga\u00e7\u00e3o ou cobertura, enquanto granjas de aves e su\u00ednos precisam ser aquecidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O IDR-Paran\u00e1 oferece o servi\u00e7o&nbsp;<a href=\"https:\/\/www.idrparana.pr.gov.br\/Pagina\/Alerta-Geada\" target=\"_blank\" rel=\"noreferrer noopener\">Alerta Geada<\/a>&nbsp;por meio de diversos canais, pelas redes sociais oficiais e pelo Disque Geada (43) 3391-4500.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DEFESA CIVIL\u00a0<\/strong>\u2013 A Defesa Civil alerta para a necessidade de medidas de prote\u00e7\u00e3o voltadas \u00e0 popula\u00e7\u00e3o mais vulner\u00e1vel, como aquela que vive nas ruas. A rede de servi\u00e7os p\u00fablicos que atua nestas a\u00e7\u00f5es, que envolve as secretarias municipais de Assist\u00eancia Social, Sa\u00fade e Agricultura, entre outras, e o Corpo de Bombeiros, j\u00e1 foi acionada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A popula\u00e7\u00e3o em geral tamb\u00e9m pode receber alertas sobre eventos clim\u00e1ticos extremos, de acordo com a regi\u00e3o. Basta enviar um SMS para o n\u00famero 40199 com o CEP do local de resid\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>DOA\u00c7\u00c3O&nbsp;<\/strong>\u2013 Para ajudar a proteger quem precisa, o Estado lan\u00e7a nesta ter\u00e7a-feira (17) a&nbsp;<a href=\"https:\/\/www.aen.pr.gov.br\/Noticia\/Governo-do-Estado-lanca-campanha-Aquece-Parana-nesta-terca-feira\" target=\"_blank\" rel=\"noreferrer noopener\">campanha \u201cAquece Paran\u00e1\u201d<\/a>, que receber\u00e1 doa\u00e7\u00f5es de cobertores e roupas, como agasalhos e casacos destinados \u00e0 popula\u00e7\u00e3o mais vulner\u00e1vel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A chegada de uma massa de ar polar vai derrubar as temperaturas no Paran\u00e1 a partir desta ter\u00e7a-feira A chegada de uma massa de ar polar vai derrubar as temperaturas no Paran\u00e1 a partir desta ter\u00e7a-feira (17), com expectativa de zero grau no extremo Sul do Estado. De acordo a com previs\u00e3o, o vento intenso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-9114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clima"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=9114"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9114\/revisions"}],"predecessor-version":[{"id":9116,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/9114\/revisions\/9116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/9115"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=9114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=9114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=9114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}