{"id":7799,"date":"2022-03-30T16:35:09","date_gmt":"2022-03-30T19:35:09","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=7799"},"modified":"2022-03-30T16:35:11","modified_gmt":"2022-03-30T19:35:11","slug":"foz-consolida-hub-logistico-com-chegada-de-ramal-da-ferroeste","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2022\/03\/30\/foz-consolida-hub-logistico-com-chegada-de-ramal-da-ferroeste\/","title":{"rendered":"<br>Foz consolida hub log\u00edstico com chegada de ramal da Ferroeste"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Governador Ratinho Junior recebeu o Evtea da nova ferrovia e destacou ainda as obras conveniadas com a Itaipu<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Foto: AEN.<br><br><\/em>A chegada do ramal da Ferroste vai consolidar Foz do Igua\u00e7u como um hub log\u00edstico. A afirma\u00e7\u00e3o \u00e9 do prefeito Chico Brasileiro que acompanhou, nesta ter\u00e7a-feira, 29, a entrega ao governador Ratinho Junior do Estudo de Viabilidade T\u00e9cnica, Econ\u00f4mica e Ambiental (Evtea) do projeto da Nova Ferroeste, que inclui o ramal ligando Cascavel e a regi\u00e3o de fronteira do Brasil com a Argentina e o Paraguai.<br><br>&#8220;Foz se consolida cada vez mais como hub log\u00edstico&#8221;, disse Chico Brasileiro, no Pal\u00e1cio Igua\u00e7u em Curitiba. &#8220;A extens\u00e3o da Ferroeste at\u00e9 nossa cidade vai transformar a fronteira ainda mais forte no transporte de gr\u00e3os. O ramal ferrovi\u00e1rio tamb\u00e9m ir\u00e1 fortalecer o turismo, j\u00e1 que o passeio de trem do litoral at\u00e9 Foz \u00e9 um desejo de muitos turistas&#8221;, ressaltou.<br><br>Na solenidade, Ratinho Junior assinou ainda as ordens de servi\u00e7o de R$ 2,5 bilh\u00f5es para obras de infraestrutura e parte delas compreende as conveniadas com a Itaipu Binaacional no oeste do Paran\u00e1. Entre as a\u00e7\u00f5es est\u00e3o a pavimenta\u00e7\u00e3o de 26,23 quil\u00f4metros da estrada entre Ramil\u00e2ndia e Santa Helena, obra de R$ 20,4 milh\u00f5es; e a restaura\u00e7\u00e3o da Ponte Ayrton Senna em Gua\u00edra, incluindo nova ilumina\u00e7\u00e3o e pavimenta\u00e7\u00e3o de concreto da rodovia de acesso, com investimento de R$ 18,2 milh\u00f5es.<br><br>&#8220;A Itaipu Binacional \u00e9 a grande parceira de Foz e do Governo do Estado. As obras de infraestrutura, como a ponte da integra\u00e7\u00e3o e perimetral leste, s\u00e3o de grande impacto e v\u00e3o transformar a configura\u00e7\u00e3o urbana da cidade e da tr\u00edplice fronteira&#8221;, completou Chico Brasileiro, que espera ainda para 8 de abril o resultado da licita\u00e7\u00e3o que vai duplicar a Avenida das Cataratas, um investimento de R$ 186,9 milh\u00f5es.<br><br>\u201cO Paran\u00e1, um importante produtor de alimentos e que tem grandes polos industriais, precisa de grandes projetos de infraestrutura. Tiramos do papel as principais obras pendentes, como a Ponte da Integra\u00e7\u00e3o, a Boiadeira, a Rodovia dos Min\u00e9rios e a revitaliza\u00e7\u00e3o da PR-323, e nos organizamos para deixar um banco de projetos muito robusto para os pr\u00f3ximos dez anos&#8221;, disse o governador.<br><br><strong>Estudo pronto<\/strong><br><br>O Evtea, com mais de duas mil p\u00e1ginas, re\u00fane informa\u00e7\u00f5es de engenharia e socioecon\u00f4micas sobre a nova Ferroeste.&nbsp; O estudo apontou a gera\u00e7\u00e3o de mais de 300 mil empregos diretos e indiretos em 65 anos. A execu\u00e7\u00e3o da estrada de ferro com 1.304 quil\u00f4metros vai ligar Maracaju (MS) ao Porto de Paranagu\u00e1.&nbsp;<br><br>A conex\u00e3o entre Cascavel e Foz do Igua\u00e7u vai permitir a integra\u00e7\u00e3o com o Paraguai e a Argentina, tornando o estado uma central log\u00edstica da Am\u00e9rica do Sul. Atualmente est\u00e1 sob an\u00e1lise o projeto ambiental pelo Ibama, com audi\u00eancias p\u00fablicas previstas para abril.<br><br>A ferrovia, que vai passar para 49 cidades (41 delas no Paran\u00e1), deve transportar cerca de 38 milh\u00f5es de toneladas no primeiro ano de opera\u00e7\u00e3o. Destes, 26 milh\u00f5es de toneladas v\u00e3o seguir para o Porto de Paranagu\u00e1 rumo a outros pa\u00edses. Ser\u00e1 o segundo maior corredor de exporta\u00e7\u00e3o de gr\u00e3os e cont\u00eaineres refrigerados do Brasil.&nbsp;<br><br>A proposta \u00e9 colocar a ferrovia em leil\u00e3o na Bolsa de Valores do Brasil (B3), em S\u00e3o Paulo, ainda no segundo semestre&nbsp; de 2022. O cons\u00f3rcio que vencer a concorr\u00eancia ser\u00e1 respons\u00e1vel tamb\u00e9m pelas obras e poder\u00e1 explorar a ferrovia por 70 anos. O investimento \u00e9 estimado em R$ 30 bilh\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Governador Ratinho Junior recebeu o Evtea da nova ferrovia e destacou ainda as obras conveniadas com a Itaipu Foto: AEN. A chegada do ramal da Ferroste vai consolidar Foz do Igua\u00e7u como um hub log\u00edstico. A afirma\u00e7\u00e3o \u00e9 do prefeito Chico Brasileiro que acompanhou, nesta ter\u00e7a-feira, 29, a entrega ao governador Ratinho Junior do Estudo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-7799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7799"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7799\/revisions"}],"predecessor-version":[{"id":7802,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7799\/revisions\/7802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/7801"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}