{"id":3169,"date":"2021-11-30T09:58:17","date_gmt":"2021-11-30T12:58:17","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=3169"},"modified":"2021-11-30T09:58:18","modified_gmt":"2021-11-30T12:58:18","slug":"saude-reabre-agendamento-para-vacinacao-covid-nesta-terca-feira-30","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2021\/11\/30\/saude-reabre-agendamento-para-vacinacao-covid-nesta-terca-feira-30\/","title":{"rendered":"Sa\u00fade reabre agendamento para vacina\u00e7\u00e3o covid nesta ter\u00e7a-feira (30)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Doses ser\u00e3o aplicadas at\u00e9 sexta-feira (04) na maior parte das UBS; aqueles que n\u00e3o conseguirem agendar tamb\u00e9m podem procurar diretamente as unidades<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Secretaria Municipal de Sa\u00fade reabriu nesta ter\u00e7a-feira (30) o agendamento para a vacina\u00e7\u00e3o contra a covid-19 para pessoas a partir de 12 anos de idade que ainda n\u00e3o tomaram a primeira dose e para a dose de refor\u00e7o daqueles que tomaram a segunda dose h\u00e1 pelo menos cinco meses.\u00a0<br><br>O agendamento pode ser feito no site vacinacao.pmfi.pr.gov. As pessoas que est\u00e3o com a segunda dose atrasada tamb\u00e9m poder\u00e3o marcar data, hor\u00e1rio e local para receber a vacina. As doses ser\u00e3o aplicadas na maior parte das 29 Unidades B\u00e1sicas de Sa\u00fade do munic\u00edpio, entre ter\u00e7a e sexta-feira (03).\u00a0<br><br>A secret\u00e1ria municipal de Sa\u00fade, Rosa Maria Jer\u00f4nymo, informa que o agendamento foi aberto para que as pessoas possam se organizar e evitem transtornos para receber a imuniza\u00e7\u00e3o. Mas, conforme ela, aqueles que buscarem as unidades de sa\u00fade ser\u00e3o atendidos mesmo sem o hor\u00e1rio agendado. Tamb\u00e9m poder\u00e3o antecipar a segunda dose aqueles que t\u00eam a data na carteirinha de vacina\u00e7\u00e3o marcada at\u00e9 o dia 18 de dezembro.<br><br>\u201cA inten\u00e7\u00e3o \u00e9 que o maior n\u00famero de pessoas poss\u00edvel compare\u00e7a para tomar as doses de refor\u00e7o. Todos aqueles que tiverem tomado a segunda dose h\u00e1 pelo menos cinco meses podem receb\u00ea-la\u201d, afirma Rosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><br><\/strong>\u201cO refor\u00e7o \u00e9 fundamental para que possamos manter o n\u00famero reduzido de casos e de \u00f3bitos pela covid, especialmente agora que se aproximam as festividades. E vale ressaltar: precisamos continuar nos cuidando, com o uso de m\u00e1scara e a frequente higieniza\u00e7\u00e3o das m\u00e3os\u201d, ressalta a secret\u00e1ria.\u00a0<br><br><strong>Balan\u00e7o<br><br><\/strong>Foz do Igua\u00e7u recebeu at\u00e9 hoje 471.625 doses de vacina contra a covid, das quais 442.669 doses j\u00e1 foram aplicadas. Da popula\u00e7\u00e3o adulta estimada pelo Ipardes, 109,2% recebeu a primeira dose, e 99,9% est\u00e3o completamente imunizados, com as duas doses. Em rela\u00e7\u00e3o \u00e0 vacina\u00e7\u00e3o dos adolescentes, 83,69% recebeu a primeira dose e 8,16% est\u00e3o totalmente imunizados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <em>Foto: Christian Rizzi\/PMFI.<\/em><br> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Doses ser\u00e3o aplicadas at\u00e9 sexta-feira (04) na maior parte das UBS; aqueles que n\u00e3o conseguirem agendar tamb\u00e9m podem procurar diretamente as unidades A Secretaria Municipal de Sa\u00fade reabriu nesta ter\u00e7a-feira (30) o agendamento para a vacina\u00e7\u00e3o contra a covid-19 para pessoas a partir de 12 anos de idade que ainda n\u00e3o tomaram a primeira dose [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[],"class_list":["post-3169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-covid-19"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3169"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3169\/revisions"}],"predecessor-version":[{"id":3171,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3169\/revisions\/3171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/3170"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}