{"id":28715,"date":"2026-03-28T12:41:28","date_gmt":"2026-03-28T15:41:28","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=28715"},"modified":"2026-03-29T12:57:46","modified_gmt":"2026-03-29T15:57:46","slug":"receita-federal-apreende-310-ampolas-de-medicamento-emagrecedor-na-ponte-da-amizade","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2026\/03\/28\/receita-federal-apreende-310-ampolas-de-medicamento-emagrecedor-na-ponte-da-amizade\/","title":{"rendered":"Receita Federal apreende 310 ampolas de medicamento emagrecedor na Ponte da Amizade"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Subst\u00e2ncias estavam ocultas em bolsas durante abordagem de rotina<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neste s\u00e1bado (28\/03), durante fiscaliza\u00e7\u00e3o de rotina realizada na Aduana da Ponte Internacional da Amizade, em Foz do Igua\u00e7u, servidores da Receita Federal abordaram um cidad\u00e3o brasileiro que transitava de motocicleta transportando medicamentos emagrecedores de forma irregular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na verifica\u00e7\u00e3o, foram encontradas 310 ampolas de tirzepatida ocultas em tr\u00eas bolsas femininas que estavam em posse do viajante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O homem foi encaminhado \u00e0 Delegacia da Pol\u00edcia Federal para a ado\u00e7\u00e3o das provid\u00eancias legais cab\u00edveis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Receita Federal refor\u00e7a seu compromisso no combate ao contrabando e a outros crimes transfronteiri\u00e7os, atuando permanentemente na prote\u00e7\u00e3o das fronteiras e da sociedade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assessoria de Comunica\u00e7\u00e3o da Alf\u00e2ndega da Receita Federal em Foz do Igua\u00e7u<\/p>\n\n\n\n<figure class=\"wp-block-video\"><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Subst\u00e2ncias estavam ocultas em bolsas durante abordagem de rotina Neste s\u00e1bado (28\/03), durante fiscaliza\u00e7\u00e3o de rotina realizada na Aduana da Ponte Internacional da Amizade, em Foz do Igua\u00e7u, servidores da Receita Federal abordaram um cidad\u00e3o brasileiro que transitava de motocicleta transportando medicamentos emagrecedores de forma irregular. Na verifica\u00e7\u00e3o, foram encontradas 310 ampolas de tirzepatida ocultas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28716,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[26,4,21],"tags":[],"class_list":["post-28715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-cidade","category-fronteira"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=28715"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28715\/revisions"}],"predecessor-version":[{"id":28717,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28715\/revisions\/28717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/28716"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=28715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=28715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=28715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}