{"id":27854,"date":"2026-01-12T21:39:56","date_gmt":"2026-01-13T00:39:56","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=27854"},"modified":"2026-01-12T21:39:57","modified_gmt":"2026-01-13T00:39:57","slug":"mais-engenharia-contabiliza-70-projetos-de-50-municipios-paranaenses","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2026\/01\/12\/mais-engenharia-contabiliza-70-projetos-de-50-municipios-paranaenses\/","title":{"rendered":"Mais Engenharia contabiliza 70 projetos de 50 munic\u00edpios paranaenses"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Lan\u00e7amento do projeto Mais Engenharia, em junho do ano passado. Foto: Rubens Fraulini\/Itaipu Binacional.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Balan\u00e7o de programa apoiado pela Itaipu foi divulgado pelo Conselho Regional de Engenharia e Agronomia do Paran\u00e1<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lan\u00e7ado em junho de 2025, pela Itaipu Binacional e parceiros, o Programa Mais Engenharia j\u00e1 contabiliza aproximadamente 70 projetos (encaminhados ou em fase de elabora\u00e7\u00e3o), de 50 munic\u00edpios paranaenses, com expectativa de capta\u00e7\u00e3o de R$ 100 milh\u00f5es. Os n\u00fameros constam de levantamento feito pelo Conselho Regional de Engenharia e Agronomia do Paran\u00e1 \u2013 Crea-PR e divulgados nesta semana. Tamb\u00e9m faz parte da parceria a Universidade Estadual de Ponta Grossa (UEPG).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O objetivo do programa \u00e9 capacitar profissionais para elabora\u00e7\u00e3o de projetos de infraestrutura e capta\u00e7\u00e3o de recursos para obras p\u00fablicas, especialmente nos munic\u00edpios com menor \u00cdndice de Desenvolvimento Humano Municipal (IDHM). Para isso, promove uma a\u00e7\u00e3o integrada entre estudantes, rec\u00e9m-formados, servidores p\u00fablicos municipais e institui\u00e7\u00f5es parceiras. &nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cConseguimos elaborar um projeto de pavimenta\u00e7\u00e3o que j\u00e1 foi encaminhado para an\u00e1lise do Paran\u00e1 Cidade para obten\u00e7\u00e3o de recursos e tamb\u00e9m estamos desenvolvendo os projetos de engenharia para uma capela mortu\u00e1ria em um dos distritos do munic\u00edpio. Sem o apoio do Mais Engenharia, dificilmente seria poss\u00edvel finalizar essas demandas dentro do prazo\u201d, afirmou o engenheiro civil Igor Alipio Bresola Carabolante, residente t\u00e9cnico do programa no munic\u00edpio de S\u00e3o Pedro do Igua\u00e7u.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cAo apoiar a elabora\u00e7\u00e3o de projetos de infraestrutura, o programa contribui diretamente para o desenvolvimento regional, reduz desigualdades e fortalece pol\u00edticas p\u00fablicas nas \u00e1reas de mobilidade, sa\u00fade, educa\u00e7\u00e3o e assist\u00eancia social\u201d, comentou o diretor-geral brasileiro da Itaipu, Enio Verri.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>De casas populares a barrac\u00f5es industriais<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Regional Cascavel concentra um dos maiores conjuntos de projetos elaborados pelo programa, de acordo com o Crea-PR. Em Guarania\u00e7u, foram desenvolvidos projetos de casas populares de at\u00e9 70 metros quadrados. Campo Bonito recebeu projeto de amplia\u00e7\u00e3o de CMEI. Em Ibema, foi elaborado projeto de ciclovia. Diamante D\u2019Oeste foi atendido com projetos de barrac\u00e3o industrial e de CRAS, incluindo terraplenagem, implanta\u00e7\u00e3o e sistemas sanit\u00e1rios. S\u00e3o Pedro do Igua\u00e7u recebeu projetos de reforma e amplia\u00e7\u00e3o de edifica\u00e7\u00f5es p\u00fablicas, enquanto Santa Maria do Oeste teve a convers\u00e3o do projeto do lago municipal para a metodologia BIM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na Regional Apucarana, o programa viabilizou projetos voltados a equipamentos p\u00fablicos e estruturas comunit\u00e1rias. Em Godoy Moreira, foram elaborados projetos de playground e de centro de eventos. Grandes Rios recebeu projeto de infraestrutura modular. Em Jardim Alegre, foram desenvolvidos projetos de salas em wood frame e de centro de conviv\u00eancia. J\u00e1 em Cafeara, o programa atendeu demandas para a implanta\u00e7\u00e3o de um CRAS e a\u00e7\u00f5es vinculadas ao Programa Inf\u00e2ncia Feliz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na Regional Guarapuava, os projetos atendem demandas de edifica\u00e7\u00f5es p\u00fablicas, requalifica\u00e7\u00e3o urbana e espa\u00e7os comunit\u00e1rios, contribuindo para a organiza\u00e7\u00e3o t\u00e9cnica de propostas voltadas \u00e0 execu\u00e7\u00e3o de obras e \u00e0 capta\u00e7\u00e3o de recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na Regional Londrina, Santana do Itarar\u00e9 foi atendido com dois projetos, sendo um de amplia\u00e7\u00e3o de complexo esportivo e outro de reforma de espa\u00e7o em unidade b\u00e1sica de sa\u00fade, com foco no atendimento a pessoas com transtorno do espectro autista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na Regional Maring\u00e1, Amapor\u00e3 recebeu projeto de recapeamento de vias urbanas. Planaltina do Paran\u00e1 foi atendida com projeto de quadra poliesportiva. Corumbata\u00ed do Sul contou com projetos de reforma e constru\u00e7\u00e3o no centro esportivo municipal. O levantamento tamb\u00e9m registra projetos em Esperan\u00e7a Nova. Em Mato Rico, foram elaborados projetos de barrac\u00e3o industrial, quadra do programa Meu Campinho e pavimenta\u00e7\u00e3o de vias urbanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na Regional Pato Branco, Coronel Domingos Soares recebeu projeto de reforma de posto de sa\u00fade. Renascen\u00e7a foi atendida com projeto de recapeamento de vias urbanas. Hon\u00f3rio Serpa contou com projeto de pavimenta\u00e7\u00e3o de estrada vicinal. Boa Esperan\u00e7a do Igua\u00e7u recebeu projeto de casa mortu\u00e1ria, enquanto Manfrin\u00f3polis foi atendida com projeto de pavimenta\u00e7\u00e3o ligando a sede ao distrito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E na Regional Ponta Grossa, o munic\u00edpio de Reserva recebeu projeto de reforma da quadra Anta Magra. S\u00e3o Jo\u00e3o do Triunfo foi contemplado com projeto de recapeamento asf\u00e1ltico de vias urbanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os engenheiros civis que atuam no programa foram selecionados por edital, com at\u00e9 tr\u00eas anos de formados. Eles atuam diretamente nas prefeituras e recebem bolsa mensal, benef\u00edcios e equipamentos compat\u00edveis com a metodologia BIM. Paralelamente, participam do curso de Especializa\u00e7\u00e3o em Gest\u00e3o P\u00fablica em Engenharia e Desenvolvimento Sustent\u00e1vel, ofertado pela UEPG. O programa tamb\u00e9m envolve estudantes de Engenharia Civil integrantes do CreaJr-PR, que atuam como estagi\u00e1rios supervisionados em projetos reais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Entrega de computadores<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte das a\u00e7\u00f5es de estrutura\u00e7\u00e3o do Mais Engenharia, o Crea-PR realizou no final do ano a entrega de computadores aos munic\u00edpios participantes. Gerentes e profissionais do Conselho estiveram presencialmente nas prefeituras para realizar a entrega dos equipamentos, refor\u00e7ando o acompanhamento direto do programa e a proximidade com as administra\u00e7\u00f5es municipais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>* com informa\u00e7\u00f5es do Conselho Regional de Engenharia e Agronomia do Paran\u00e1 \u2013 Crea-PR.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lan\u00e7amento do projeto Mais Engenharia, em junho do ano passado. Foto: Rubens Fraulini\/Itaipu Binacional. Balan\u00e7o de programa apoiado pela Itaipu foi divulgado pelo Conselho Regional de Engenharia e Agronomia do Paran\u00e1 Lan\u00e7ado em junho de 2025, pela Itaipu Binacional e parceiros, o Programa Mais Engenharia j\u00e1 contabiliza aproximadamente 70 projetos (encaminhados ou em fase de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,4,11],"tags":[],"class_list":["post-27854","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-cidade","category-itaipu"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27854"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27854\/revisions"}],"predecessor-version":[{"id":27856,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27854\/revisions\/27856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/27855"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}