{"id":27835,"date":"2026-01-11T13:45:32","date_gmt":"2026-01-11T16:45:32","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=27835"},"modified":"2026-01-11T13:50:10","modified_gmt":"2026-01-11T16:50:10","slug":"parque-nacional-do-iguacu-celebra-87-anos-e-inicia-uma-nova-fase-com-o-lancamento-do-parque-2030","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2026\/01\/11\/parque-nacional-do-iguacu-celebra-87-anos-e-inicia-uma-nova-fase-com-o-lancamento-do-parque-2030\/","title":{"rendered":"Parque Nacional do Igua\u00e7u celebra 87 anos e inicia uma nova fase com o lan\u00e7amento do Parque 2030"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Programa que projeta o futuro do parque e tem um investimento de R$ 600 milh\u00f5es foi apresentado nesta sexta-feira, abrindo oficialmente as celebra\u00e7\u00f5es do anivers\u00e1rio<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>As comemora\u00e7\u00f5es dos 87 anos do Parque Nacional do Igua\u00e7u tiveram in\u00edcio oficialmente nesta sexta-feira, 9, com a recep\u00e7\u00e3o de autoridades e convidados no Centro de Visitantes. No evento, a Urbia+Cataratas, gestora da visita\u00e7\u00e3o tur\u00edstica da unidade, e o ICMBio apresentaram o Parque 2030, um plano que contempla R$ 600 milh\u00f5es em investimentos e que vai colocar o lar das Cataratas do Igua\u00e7u entre as melhores experi\u00eancias de conex\u00e3o com a natureza do mundo, valorizando ainda mais a sua ess\u00eancia de preserva\u00e7\u00e3o e encantamento.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>As comemora\u00e7\u00f5es continuam no s\u00e1bado, 10 de janeiro, com atividades gratuitas aos visitantes, sendo necess\u00e1ria apenas a compra do ingresso.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Criado em 10 de janeiro de 1939, o Parque Nacional do Igua\u00e7u se tornou refer\u00eancia internacional em conserva\u00e7\u00e3o ambiental e gest\u00e3o de \u00e1reas protegidas. A cerim\u00f4nia relembrou essa trajet\u00f3ria e destacou a conquista recente. Em 2025, o parque registrou mais de 2.058.000 visitantes, o maior n\u00famero de sua hist\u00f3ria, com crescimento de 8,7% em rela\u00e7\u00e3o ao ano anterior e superando os \u00edndices do per\u00edodo pr\u00e9-pandemia.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Criado em 10 de janeiro de 1939, o Parque Nacional do Igua\u00e7u se tornou refer\u00eancia internacional em conserva\u00e7\u00e3o ambiental e gest\u00e3o de \u00e1reas protegidas. A cerim\u00f4nia relembrou essa trajet\u00f3ria e destacou a conquista recente. Em 2025, o parque registrou mais de 2.058.000 visitantes, o maior n\u00famero de sua hist\u00f3ria, com crescimento de 8,7% em rela\u00e7\u00e3o ao ano anterior e superando os \u00edndices do per\u00edodo pr\u00e9-pandemia.&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>\u201cO resultado refor\u00e7a a relev\u00e2ncia do destino para o turismo nacional e internacional e o papel estrat\u00e9gico do parque no desenvolvimento regional. Milhares de pessoas passam por aqui todos os dias gra\u00e7as ao trabalho realizado h\u00e1 87 anos, que ajuda a cumprir o prop\u00f3sito firmado naquela \u00e9poca: conservar este ambiente, promover o conhecimento e a educa\u00e7\u00e3o ambiental\u201d, explica o CEO da Urbia+Cataratas, Mario Macedo Junior.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Parque Nacional do Igua\u00e7u 2030 \u2014 O programa tem o objetivo de ampliar a vis\u00e3o de que a unidade \u00e9 mais que uma maravilha da natureza, \u00e9 uma refer\u00eancia em turismo respons\u00e1vel, com a\u00e7\u00f5es voltadas \u00e0 conserva\u00e7\u00e3o da biodiversidade, inova\u00e7\u00e3o e desenvolvimento regional.&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Desde que a Urbia+Cataratas assumiu a gest\u00e3o, em 2022, vem investindo em novas atra\u00e7\u00f5es e experi\u00eancias. At\u00e9 2030, a concession\u00e1ria tem o compromisso de aportar R$ 600 milh\u00f5es na unidade. Os investimentos nos tr\u00eas primeiros anos tiveram o objetivo de tornar o local mais inclusivo, proporcionando outras experi\u00eancias al\u00e9m das Cataratas do Igua\u00e7u. Foram entregues a Ciclovia das Cataratas, o Circuito S\u00e3o Jo\u00e3o, o Espa\u00e7o Usina e o conjunto de trilhas reabertas e revitalizadas, al\u00e9m de novos roteiros que permitem ao turista contemplar as Cataratas ao amanhecer, p\u00f4r do sol ou anoitecer; e dois novos restaurantes.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Para os pr\u00f3ximos anos, as novidades previstas incluem o Circuito de Aventura, com trilhas suspensas, tirolesas, tren\u00f3s e torres de observa\u00e7\u00e3o \u00e0s margens do Rio Igua\u00e7u; a nova Trilha das Cataratas, que ser\u00e1 totalmente revitalizada, com novos mirantes, trechos duplicados e amplia\u00e7\u00e3o da passarela com vista para a Garganta do Diabo; a revitaliza\u00e7\u00e3o do tradicional Espa\u00e7o Porto Canoas, que ganhar\u00e1 conceito arquitet\u00f4nico renovado, deque panor\u00e2mico e \u00e1reas para eventos. Al\u00e9m da expans\u00e3o da visita\u00e7\u00e3o para outros polos, levando estrutura e oportunidades a munic\u00edpios como Capanema, S\u00e3o Miguel do Igua\u00e7u e C\u00e9u Azul, que est\u00e3o no entorno do parque.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>O Parque Nacional do Igua\u00e7u 2030 tem ainda iniciativas sociais e ambientais que v\u00e3o al\u00e9m do aporte em experi\u00eancias e infraestrutura, como a neutraliza\u00e7\u00e3o completa das emiss\u00f5es de carbono, a conquista de certifica\u00e7\u00f5es ambientais in\u00e9ditas e a\u00e7\u00f5es de fortalecimento da economia local. Atualmente, 74% dos fornecedores de produtos e servi\u00e7os do parque s\u00e3o locais, fomentando o desenvolvimento regional. Tamb\u00e9m investe em institui\u00e7\u00f5es e equipamentos de pesquisa e preserva\u00e7\u00e3o da fauna e da flora.&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>\u201cDiversas equipes do ICMBio, da Pol\u00edcia Militar Ambiental, Pol\u00edcia Federal, entre outras entidades, dedicam muitas horas de trabalho para cuidar do Parque Nacional. Ter parcerias \u00e9 fundamental para dar suporte a esse trabalho. Para o Parque 2030, tivemos o envolvimento das comunidades dos munic\u00edpios abrangidos pela unidade para entender os impactos socioecon\u00f4micos, do ecoturismo e dos atrativos do entorno. A gente est\u00e1 trabalhando para implantar um outro modelo de turismo, que valoriza experi\u00eancias mais profundas e conex\u00e3o com a natureza. Contamos com a pot\u00eancia nas Cataratas para atrair esses visitantes e ampliar cada vez mais a preserva\u00e7\u00e3o por meio de pesquisas e estudos\u201d, exp\u00f4s o chefe do Parque Nacional do Igua\u00e7u, Jos\u00e9 Ulisses dos Santos.&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>No evento, estiveram presentes o prefeito de Foz do Igua\u00e7u, general Joaquim Silva e Luna; o diretor-geral em exerc\u00edcio do lado brasileiro da usina de Itaipu, Luiz Fernando Ferreira Delazari; representantes das concession\u00e1rias do Parque Nacional do Igua\u00e7u, Helisul e Macuco Safari, e do Hotel das Cataratas, A Belmond Hotel.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Anivers\u00e1rio ser\u00e1 marcado por atra\u00e7\u00f5es para o p\u00fablico \u2014<\/strong>&nbsp;Durante todo o s\u00e1bado, os visitantes do parque ter\u00e3o atra\u00e7\u00f5es especiais, que incluem a Feirinha do Parque, pintura facial, shows musicais, pain\u00e9is interativos, exposi\u00e7\u00f5es art\u00edsticas, al\u00e9m da oficina Postais do Parque, sess\u00e3o de ioga no Hotel das Cataratas e atividades na Escola Parque. A programa\u00e7\u00e3o completa est\u00e1 no https:\/\/cataratasdoiguacu.com.br\/blog\/programacao-especial-de-aniversario-neste-sabado\/.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Assista \u00e0 webs\u00e9rie Igua\u00e7u 2030 \u2014<\/strong>&nbsp;Com o lan\u00e7amento do programa durante a cerim\u00f4nia, foi exibido tamb\u00e9m o primeiro epis\u00f3dio da webs\u00e9rie Igua\u00e7u 2030, \u201cA natureza est\u00e1 em movimento\u201d, que introduz o p\u00fablico ao projeto robusto da concession\u00e1ria Urbia+Cataratas. O plano e o primeiro epis\u00f3dio est\u00e3o dispon\u00edveis no site oficial, acesse: https:\/\/cataratasdoiguacu.com.br\/novo-tempo\/.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Garanta a participa\u00e7\u00e3o com seu ingresso antecipado \u2014&nbsp;<\/strong>Para evitar filas no acesso ao parque, a orienta\u00e7\u00e3o \u00e9 adquirir o ingresso com anteced\u00eancia pelo site oficial: cataratasdoiguacu.com.br. Assim, o visitante garante agilidade na entrada e mais previsibilidade no planejamento da visita. Chegar no primeiro hor\u00e1rio, \u00e0s 8h, assegura um passeio mais tranquilo e o contato com as atra\u00e7\u00f5es do anivers\u00e1rio logo na chegada.<br><br>Moradores dos 14 munic\u00edpios vizinhos possuem 80% de desconto com o Passe Comunidade ao apresentarem comprovante de resid\u00eancia. Veja os documentos necess\u00e1rios e adquira o ingresso: https:\/\/cataratasdoiguacu.com.br\/ajuda-e-cuidados\/passe-comunidade\/.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Servi\u00e7o \u2014 87 anos do Parque Nacional do Igua\u00e7u<\/strong><br>Data: 10 de janeiro&nbsp;<br>Hor\u00e1rio: das 8h \u00e0s 16h<br>Programa\u00e7\u00e3o aberta no Centro de Visitantes, Espa\u00e7o Porto Canoas, Espa\u00e7o Usina e Escola Parque. Confira no:&nbsp;<br>https:\/\/cataratasdoiguacu.com.br\/blog\/programacao-especial-de-aniversario-neste-sabado\/<br>Aula de ioga: \u00e0s 9h, no Hotel das Cataratas, mediante inscri\u00e7\u00e3o pr\u00e9via<br>Ingressos antecipados: cataratasdoiguacu.com.br<br><br><strong>Sobre o Parque Nacional do Igua\u00e7u \u2014&nbsp;<\/strong>Reconhecido como Patrim\u00f4nio Mundial Natural pela UNESCO, o Parque Nacional do Igua\u00e7u \u00e9 administrado pelo Instituto Chico Mendes de Conserva\u00e7\u00e3o da Biodiversidade (ICMBio) e tem sua visita\u00e7\u00e3o tur\u00edstica gerida pela Urbia+Cataratas. O destino \u00e9 refer\u00eancia internacional em turismo sustent\u00e1vel e foi eleito, pelo Tripadvisor Travelers\u2019 Choice Best of the Best 2025, a principal atra\u00e7\u00e3o tur\u00edstica do Brasil e da Am\u00e9rica Latina.<br><br>Cr\u00e9dito das imagens: Urbia+Cataratas\/Eagle Eye Company<br><br><strong>Mais informa\u00e7\u00f5es:&nbsp;<\/strong><br>contato@catarataspni.com.br&nbsp;<br>cataratasdoiguacu.com.br<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"27842\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-1-1024x681.jpeg?v=1768150191\" alt=\"\" class=\"wp-image-27842\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-1-1024x681.jpeg?v=1768150191 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-1-300x200.jpeg?v=1768150191 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-1-768x511.jpeg?v=1768150191 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-1-1536x1021.jpeg?v=1768150191 1536w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-1.jpeg?v=1768150191 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"27845\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-1-1024x681.jpeg?v=1768150192\" alt=\"\" class=\"wp-image-27845\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-1-1024x681.jpeg?v=1768150192 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-1-300x200.jpeg?v=1768150192 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-1-768x511.jpeg?v=1768150192 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-1-1536x1021.jpeg?v=1768150192 1536w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-1.jpeg?v=1768150192 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"27847\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-1024x681.jpeg?v=1768150192\" alt=\"\" class=\"wp-image-27847\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-1024x681.jpeg?v=1768150192 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-300x200.jpeg?v=1768150192 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-768x511.jpeg?v=1768150192 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50-1536x1021.jpeg?v=1768150192 1536w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.50.jpeg?v=1768150192 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"27848\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.48-1024x681.jpeg?v=1768150192\" alt=\"\" class=\"wp-image-27848\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.48-1024x681.jpeg?v=1768150192 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.48-300x200.jpeg?v=1768150192 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.48-768x511.jpeg?v=1768150192 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.48-1536x1021.jpeg?v=1768150192 1536w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.48.jpeg?v=1768150192 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"27840\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-1-1024x682.jpeg?v=1768150188\" alt=\"\" class=\"wp-image-27840\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-1-1024x682.jpeg?v=1768150188 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-1-300x200.jpeg?v=1768150188 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-1-768x512.jpeg?v=1768150188 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-1-1536x1023.jpeg?v=1768150188 1536w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-1.jpeg?v=1768150188 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"27841\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.52-1024x681.jpeg?v=1768150191\" alt=\"\" class=\"wp-image-27841\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.52-1024x681.jpeg?v=1768150191 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.52-300x200.jpeg?v=1768150191 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.52-768x511.jpeg?v=1768150191 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.52-1536x1021.jpeg?v=1768150191 1536w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.52.jpeg?v=1768150191 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"27839\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-2_1-1024x681.jpeg?v=1768150183\" alt=\"\" class=\"wp-image-27839\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-2_1-1024x681.jpeg?v=1768150183 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-2_1-300x200.jpeg?v=1768150183 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-2_1-768x511.jpeg?v=1768150183 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-2_1-1536x1021.jpeg?v=1768150183 1536w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51-2_1.jpeg?v=1768150183 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"27843\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-1024x682.jpeg?v=1768150191\" alt=\"\" class=\"wp-image-27843\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-1024x682.jpeg?v=1768150191 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-300x200.jpeg?v=1768150191 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-768x512.jpeg?v=1768150191 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49-1536x1023.jpeg?v=1768150191 1536w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.49.jpeg?v=1768150191 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" data-id=\"27846\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.46-1-1024x681.jpeg?v=1768150192\" alt=\"\" class=\"wp-image-27846\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.46-1-1024x681.jpeg?v=1768150192 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.46-1-300x200.jpeg?v=1768150192 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.46-1-768x511.jpeg?v=1768150192 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.46-1-1536x1021.jpeg?v=1768150192 1536w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.46-1.jpeg?v=1768150192 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"27844\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51_1-1024x682.jpeg?v=1768150192\" alt=\"\" class=\"wp-image-27844\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51_1-1024x682.jpeg?v=1768150192 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51_1-300x200.jpeg?v=1768150192 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51_1-768x512.jpeg?v=1768150192 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51_1-1536x1023.jpeg?v=1768150192 1536w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/WhatsApp-Image-2026-01-09-at-16.21.51_1.jpeg?v=1768150192 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Programa que projeta o futuro do parque e tem um investimento de R$ 600 milh\u00f5es foi apresentado nesta sexta-feira, abrindo oficialmente as celebra\u00e7\u00f5es do anivers\u00e1rio As comemora\u00e7\u00f5es dos 87 anos do Parque Nacional do Igua\u00e7u tiveram in\u00edcio oficialmente nesta sexta-feira, 9, com a recep\u00e7\u00e3o de autoridades e convidados no Centro de Visitantes. No evento, a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26,4,13],"tags":[],"class_list":["post-27835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-cidade","category-entretenimento"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27835"}],"version-history":[{"count":2,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27835\/revisions"}],"predecessor-version":[{"id":27849,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27835\/revisions\/27849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/27836"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}