{"id":27814,"date":"2026-01-11T13:20:35","date_gmt":"2026-01-11T16:20:35","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=27814"},"modified":"2026-01-11T13:20:36","modified_gmt":"2026-01-11T16:20:36","slug":"tornado-atinge-sao-jose-dos-pinhais-defesa-civil-estadual-envia-26-mil-telhas-para-moradores","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2026\/01\/11\/tornado-atinge-sao-jose-dos-pinhais-defesa-civil-estadual-envia-26-mil-telhas-para-moradores\/","title":{"rendered":"Tornado atinge S\u00e3o Jose dos Pinhais, Defesa Civil Estadual envia 2,6 mil telhas para moradores"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Estado vem acompanhando o cen\u00e1rio desde que um tornado atingiu o munic\u00edpio da Regi\u00e3o Metropolitana de Curitiba no \u00faltimo s\u00e1bado (10), atingindo 350 resid\u00eancias.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Defesa Civil Estadual encaminhou na manh\u00e3 deste domingo (11) uma carga de 2,6 mil telhas para auxiliar os moradores do bairro Guatup\u00ea, em S\u00e3o Jos\u00e9 dos Pinhais. S\u00e1bado (10), o munic\u00edpio da Regi\u00e3o Metropolitana de Curitiba (RMC) foi atingido por um tornado que danificou 350 resid\u00eancias, impactando 1,2 mil pessoas.&nbsp;Antes, a Defesa Civil do Paran\u00e1 j\u00e1 havia enviado 310 metros de lona para ajudar os moradores atingidos pelo tornado<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os moradores de duas resid\u00eancias ficaram desalojados, indo para a casa de familiares. Duas pessoas tiveram ferimentos leves durante o evento e foram encaminhadas para as unidades de atendimento em sa\u00fade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m dos danos \u00e0s edifica\u00e7\u00f5es, o tornado provocou&nbsp;queda de \u00e1rvores&nbsp;e&nbsp;problemas na rede e distribui\u00e7\u00e3o de energia el\u00e9trica, exigindo a atua\u00e7\u00e3o conjunta de diversos \u00f3rg\u00e3os. As a\u00e7\u00f5es de resposta envolveram a&nbsp;Defesa Civil municipal, o&nbsp;Corpo de Bombeiros Militar, al\u00e9m do&nbsp;da equipe regional da Defesa Civil Estadual, que prestou apoio t\u00e9cnico \u00e0s equipes locais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Defesa Civil do Paran\u00e1 segue acompanhando a situa\u00e7\u00e3o e o atendimento \u00e0 popula\u00e7\u00e3o. \u201cEssa carga de 2.600 telhas para S\u00e3o Jos\u00e9 dos Pinhais vai auxiliar as fam\u00edlias mais afetadas, ajudando para que a popula\u00e7\u00e3o possa se reestabelecer o mais r\u00e1pido poss\u00edvel\u201d, afirma Marcos Vidal, assessor de comunica\u00e7\u00e3o da Defesa Civil Estadual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>AVALIA\u00c7\u00c3O \u2013&nbsp;<\/strong>O Simepar confirmou que o fen\u00f4meno em&nbsp; S\u00e3o Jos\u00e9 dos Pinhais foi um tornado. Agora,<a href=\"https:\/\/www.parana.pr.gov.br\/aen\/Noticia\/Simepar-avalia-nivel-do-tornado-que-atingiu-Sao-Jose-dos-Pinhais-sabado\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;a equipe de meteorologistas trabalha para dimensionar o evento<\/a>&nbsp;dentro da Escala Fujita, a mesma utilizada na passagem do tornado em Rio Bonito do Igua\u00e7u, no Sudoeste, em novembro. Na ocasi\u00e3o, o tornado de Rio Bonito do Igua\u00e7u foi classificado como F4, a pen\u00faltima de intensidade dentro da escala que vai at\u00e9 cinco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ALERTAS \u2013<\/strong>&nbsp;O cadastro para receber alertas de fen\u00f4menos clim\u00e1ticos pelo celular \u00e9 gratuito. Para receber informa\u00e7\u00f5es, basta fazer o cadastro mandando um SMS com o CEP para o n\u00famero 40199.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 poss\u00edvel receber tamb\u00e9m por meio do whatsapp, basta cadastrar e interagir com o n\u00famero 61 2034-4611 para prosseguir com o cadastro. Em caso de emerg\u00eancia busque um local seguro.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"27820\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_12.12.40-1-1024x683.jpg?v=1768148293\" alt=\"\" class=\"wp-image-27820\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_12.12.40-1-1024x683.jpg?v=1768148293 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_12.12.40-1-300x200.jpg?v=1768148293 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_12.12.40-1-768x512.jpg?v=1768148293 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_12.12.40-1.jpg?v=1768148293 1348w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"599\" data-id=\"27817\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_11.51.24.jpg\" alt=\"\" class=\"wp-image-27817\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_11.51.24.jpg?v=1768148291 900w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_11.51.24-300x200.jpg?v=1768148291 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_11.51.24-768x511.jpg?v=1768148291 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"27819\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_12.12.39-1024x682.jpg?v=1768148293\" alt=\"\" class=\"wp-image-27819\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_12.12.39-1024x682.jpg?v=1768148293 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_12.12.39-300x200.jpg?v=1768148293 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_12.12.39-768x512.jpg?v=1768148293 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_12.12.39.jpg?v=1768148293 1349w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_10.34.18-1024x683.jpg?v=1768148405\" alt=\"\" class=\"wp-image-27821\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_10.34.18-1024x683.jpg?v=1768148405 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_10.34.18-300x200.jpg?v=1768148405 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_10.34.18-768x512.jpg?v=1768148405 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_10.34.18.jpg?v=1768148405 1350w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_10.34.18_1-1024x683.jpg?v=1768148413\" alt=\"\" class=\"wp-image-27822\" srcset=\"https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_10.34.18_1-1024x683.jpg?v=1768148413 1024w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_10.34.18_1-300x200.jpg?v=1768148413 300w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_10.34.18_1-768x512.jpg?v=1768148413 768w, https:\/\/acontecenafronteira.com.br\/wp-content\/uploads\/2026\/01\/whatsapp_image_2026-01-11_at_10.34.18_1.jpg?v=1768148413 1350w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Estado vem acompanhando o cen\u00e1rio desde que um tornado atingiu o munic\u00edpio da Regi\u00e3o Metropolitana de Curitiba no \u00faltimo s\u00e1bado (10), atingindo 350 resid\u00eancias. A Defesa Civil Estadual encaminhou na manh\u00e3 deste domingo (11) uma carga de 2,6 mil telhas para auxiliar os moradores do bairro Guatup\u00ea, em S\u00e3o Jos\u00e9 dos Pinhais. S\u00e1bado (10), o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,26,23],"tags":[],"class_list":["post-27814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acidente","category-brasil","category-clima"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27814"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27814\/revisions"}],"predecessor-version":[{"id":27824,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27814\/revisions\/27824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/27823"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}