{"id":21651,"date":"2025-01-09T16:54:05","date_gmt":"2025-01-09T19:54:05","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=21651"},"modified":"2025-01-09T16:54:07","modified_gmt":"2025-01-09T19:54:07","slug":"queda-de-aviao-em-ubatuba-deixa-um-morto-e-seis-feridos","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2025\/01\/09\/queda-de-aviao-em-ubatuba-deixa-um-morto-e-seis-feridos\/","title":{"rendered":"Queda de avi\u00e3o em Ubatuba deixa um morto e seis feridos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">V\u00eddeos que circulam nas redes sociais mostram o avi\u00e3o saindo do aeroporto da cidade e explodindo antes de chegar \u00e0 faixa de areia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00a0queda de avi\u00e3o em Ubatuba, no Litoral de S\u00e3o Paulo, deixou\u00a0uma pessoa morta\u00a0e outras seis feridas, conforme informou a Prefeitura da cidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uma das v\u00edtimas do\u00a0acidente a\u00e9reo em Ubatuba\u00a0seria o piloto da aeronave. Inicialmente, a Prefeitura de Ubatuba havia divulgado duas mortes, \u00e0s 10h58. No entanto, \u00e0s 11h23, o governo municipal corrigiu a informa\u00e7\u00e3o e confirmou que apenas o piloto morreu no acidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda de acordo com a Prefeitura da cidade, seis pessoas ficaram feridas e precisaram ser levadas para hospitais da regi\u00e3o. Entre todos os atendimentos, a prefeitura confirmou que cinco v\u00edtimas estavam na aeronave e outras tr\u00eas em uma pista de skate no local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro do jatinho Cessna Aircraft, de matr\u00edcula PR-GFS, modelo 525, estavam o piloto, dois adultos e duas crian\u00e7as.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"V\u00eddeo mostra momento da queda de avi\u00e3o em Ubatuba (SP) | CNN Brasil\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/AgYK-L6jybc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>V\u00eddeos que circulam nas redes sociais mostram o avi\u00e3o saindo do aeroporto da cidade e explodindo antes de chegar \u00e0 faixa de areia. A\u00a0queda de avi\u00e3o em Ubatuba, no Litoral de S\u00e3o Paulo, deixou\u00a0uma pessoa morta\u00a0e outras seis feridas, conforme informou a Prefeitura da cidade. Uma das v\u00edtimas do\u00a0acidente a\u00e9reo em Ubatuba\u00a0seria o piloto da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,26,20],"tags":[],"class_list":["post-21651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acidente","category-brasil","category-seguranca"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=21651"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21651\/revisions"}],"predecessor-version":[{"id":21653,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/21651\/revisions\/21653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/21652"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=21651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=21651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=21651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}