{"id":1912,"date":"2021-11-09T15:20:27","date_gmt":"2021-11-09T18:20:27","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=1912"},"modified":"2021-11-09T15:20:28","modified_gmt":"2021-11-09T18:20:28","slug":"plantao-covid-tem-novo-horario-de-atendimento","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2021\/11\/09\/plantao-covid-tem-novo-horario-de-atendimento\/","title":{"rendered":"Plant\u00e3o Covid tem novo hor\u00e1rio de atendimento"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A central de atendimento do Plant\u00e3o Coronav\u00edrus, passa a operar nos seguintes hor\u00e1rios: de segunda a sexta-feira, das 8h \u00e0s 22h, e aos s\u00e1bados, das 8h \u00e0s 18h. Aos domingos n\u00e3o haver\u00e1 atendimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lembrando que o Plant\u00e3o Covid \u00e9 o primeiro canal para atendimento dos casos suspeitos e agendamento de exames RT-PCR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As coletas s\u00e3o realizadas no setor da Triagem do Pronto-Socorro Respirat\u00f3rio do Hospital Municipal Padre Germano Lauck, somente mediante marca\u00e7\u00e3o pr\u00e9via via Plant\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os servi\u00e7os podem ser solicitados pelos n\u00fameros 0800-6455655 (liga\u00e7\u00e3o gratuita) e (45) 3521-1800 (whatsapp e liga\u00e7\u00e3o).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A central de atendimento do Plant\u00e3o Coronav\u00edrus, passa a operar nos seguintes hor\u00e1rios: de segunda a sexta-feira, das 8h \u00e0s 22h, e aos s\u00e1bados, das 8h \u00e0s 18h. Aos domingos n\u00e3o haver\u00e1 atendimento. Lembrando que o Plant\u00e3o Covid \u00e9 o primeiro canal para atendimento dos casos suspeitos e agendamento de exames RT-PCR. As coletas s\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4,7,10],"tags":[],"class_list":["post-1912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-covid-19","category-saude"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1912"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1912\/revisions"}],"predecessor-version":[{"id":1914,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1912\/revisions\/1914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/1913"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}