{"id":1377,"date":"2021-10-31T11:14:42","date_gmt":"2021-10-31T14:14:42","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=1377"},"modified":"2021-10-31T11:14:42","modified_gmt":"2021-10-31T14:14:42","slug":"denarc-cumpre-mandado-de-busca-e-prende-um-em-flagrante","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2021\/10\/31\/denarc-cumpre-mandado-de-busca-e-prende-um-em-flagrante\/","title":{"rendered":"DENARC CUMPRE MANDADO DE BUSCA E PRENDE UM EM FLAGRANTE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nesta sexta-feira (29), a Divis\u00e3o Estadual de Narc\u00f3ticos \u2013 DENARC, da Pol\u00edcia Civil em conjunto com equipes do Canil e Choque \u2013 Pol\u00edcia Militar, cumpriram mandado de busca e apreens\u00e3o no bairro Cidade Nova e prenderam em flagrante um suspeito, homem, 24 anos de idade pela pr\u00e1tica do crime de tr\u00e1fico de drogas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s dilig\u00eancias durante o cumprimento do mandado, foram localizados na resid\u00eancia: 60 g (sessenta gramas) de coca\u00edna, 20 g (vinte gramas) de maconha em forma de capulho, uma pistola marca Glock, 9mm, carregada com dezesseis cartuchos e dois carregadores sobressalentes, 04 balan\u00e7as de precis\u00e3o, valores em dinheiro e dois ve\u00edculos sendo um deles um Hundai\/IX35 e um Peugeot\/206.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O suspeito e as apreens\u00f5es foram encaminhadas para a Delegacia de Pol\u00edcia e apresentados a Autoridade Policial, que ap\u00f3s lavrar o flagrante encaminhou o suspeito para a Cadeia P\u00fablica Laudemir Neves, onde permanecer\u00e1 a disposi\u00e7\u00e3o da justi\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta sexta-feira (29), a Divis\u00e3o Estadual de Narc\u00f3ticos \u2013 DENARC, da Pol\u00edcia Civil em conjunto com equipes do Canil e Choque \u2013 Pol\u00edcia Militar, cumpriram mandado de busca e apreens\u00e3o no bairro Cidade Nova e prenderam em flagrante um suspeito, homem, 24 anos de idade pela pr\u00e1tica do crime de tr\u00e1fico de drogas. Ap\u00f3s dilig\u00eancias [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[],"class_list":["post-1377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade","category-policia"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1377"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1377\/revisions"}],"predecessor-version":[{"id":1379,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1377\/revisions\/1379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/1378"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}