{"id":11241,"date":"2022-07-18T14:26:49","date_gmt":"2022-07-18T17:26:49","guid":{"rendered":"https:\/\/acontecenafronteira.com.br\/?p=11241"},"modified":"2022-07-18T14:26:50","modified_gmt":"2022-07-18T17:26:50","slug":"prefeito-chico-brasileiro-sanciona-lei-que-reorganiza-quadro-de-carreiras-da-guarda-municipal","status":"publish","type":"post","link":"https:\/\/acontecenafronteira.com.br\/index.php\/2022\/07\/18\/prefeito-chico-brasileiro-sanciona-lei-que-reorganiza-quadro-de-carreiras-da-guarda-municipal\/","title":{"rendered":"Prefeito Chico Brasileiro sanciona lei que reorganiza quadro de carreiras da Guarda Municipal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A proposta \u00e9 uma luta antiga dos servidores e teve como principal articulador o falecido GM Marcelo Arruda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O prefeito Chico Brasileiro sancionou na sexta-feira (15) lei que reorganiza as carreiras funcionais dos guardas municipais e que trata do enquadramento do cargo de Guarda Municipal 1\u00aa Classe.<br><br>A lei n\u00ba 5.134 disp\u00f5e sobre a reorganiza\u00e7\u00e3o das carreiras funcionais dos servidores p\u00fablicos da Prefeitura de Foz do Igua\u00e7u e foi publicada no Di\u00e1rio Oficial do Munic\u00edpio de sexta-feira, com efeitos a partir de janeiro de 2023.<br><br>O prefeito informou que ir\u00e1 encaminhar \u00e0 C\u00e2mara Municipal a proposta de nomear a lei como Marcelo Arruda, em homenagem ao guarda municipal assassinado no dia 10 de julho, que foi o principal articulador junto ao poder p\u00fablico sobre a reorganiza\u00e7\u00e3o do quadro da GM junto ao poder p\u00fablico. \u201cEsse projeto foi uma grande bandeira do Marcelo, ent\u00e3o faremos essa homenagem para marcar a hist\u00f3ria dele em defesa \u00e0 corpora\u00e7\u00e3o e aos servidores municipais\u201d, disse o prefeito.<br><br><strong>Mudan\u00e7as<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Com a lei aprovada, foram criados a t\u00edtulo de aperfei\u00e7oamento e capacita\u00e7\u00e3o profissional, os n\u00edveis I, II e III ao cargo de Guarda Municipal 1\u00aa Classe, integrante do Grupo Ocupacional do Corpo da Guarda Municipal. Com isso, o enquadramento do servidor ocupante do cargo de GM 1\u00aa Classe em cada n\u00edvel se dar\u00e1 mediante requerimento do servidor, com in\u00edcio no ano de 2023, no m\u00eas de junho de cada ano.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>O guarda municipal Cleumar Farias, atualmente Coordenador de Tr\u00e2nsito da GM,&nbsp; fez parte da comiss\u00e3o que tratou a proposta junto ao poder p\u00fablico. Ao lado de Marcelo Arruda, Cleumar participou das reuni\u00f5es com vereadores e com o prefeito Chico Brasileiro em busca da aprova\u00e7\u00e3o da lei.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cConquistamos uma solu\u00e7\u00e3o que valoriza os servidores e n\u00e3o afeta o cofre p\u00fablico. \u00c9 uma demanda antiga, que teve in\u00edcio com nosso companheiro Marcelo Arruda. O prefeito Chico Brasileiro teve sensibilidade\u201d, ressaltou Cleumar.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O coordenador explica, ainda, que a lei aprovada \u00e9 uma corre\u00e7\u00e3o salarial, um incentivo para a qualifica\u00e7\u00e3o dos guardas municipais. Com a dificuldade de vagas para subinspetores, no quadro da institui\u00e7\u00e3o, de acordo com Cleumar, o prefeito Chico Brasileiro corrigiu a distor\u00e7\u00e3o salarial dos n\u00edveis I, II e III, de forma horizontal.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA lei vai permitir a corre\u00e7\u00e3o salarial em tr\u00eas etapas de bonifica\u00e7\u00e3o. O GM de 1\u00aa classe n\u00edvel I ter\u00e1 6% de remunera\u00e7\u00e3o, n\u00edvel II, 6% e n\u00edvel II, 3%. Em tr\u00eas anos, come\u00e7ar\u00e1 a receber o sal\u00e1rio de n\u00edvel subinspetor. Com isso, futuramente ser\u00e1 poss\u00edvel modificar a lei e subir o cargo desses servidores que j\u00e1 estar\u00e3o recebendo o sal\u00e1rio de tal\u201d, ressaltou Cleumar.<br>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o secret\u00e1rio municipal de Seguran\u00e7a P\u00fablica, tenente-coronel Marcos Antonio Jahnke, o prefeito Chico Brasileiro teve sensibilidade pela causa e reconheceu a import\u00e2ncia da proposta para os servidores. \u201cCom certeza este \u00e9 um diferencial do prefeito. Ele ouviu os guardas municipais e atendeu ao pedido dos servidores. Isso representa a valoriza\u00e7\u00e3o e humaniza\u00e7\u00e3o da GM. Ele teve sapi\u00eancia e responsabilidade ao tratar e apoiar a proposta,\u201d disse Jahnke.&nbsp;<br><br>O secret\u00e1rio destacou a import\u00e2ncia do GM Marcelo Arruda para a aprova\u00e7\u00e3o da Lei. \u201cO Marcelo foi o principal pilar para que o projeto fosse aprovado. Ele foi incans\u00e1vel. Participou de todas as reuni\u00f5es. Lamentamos que ele n\u00e3o esteja aqui para ver essa vit\u00f3ria, mas tenho certeza que ele est\u00e1 orgulhoso, pois a miss\u00e3o foi cumprida\u201d, finalizou.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A proposta \u00e9 uma luta antiga dos servidores e teve como principal articulador o falecido GM Marcelo Arruda O prefeito Chico Brasileiro sancionou na sexta-feira (15) lei que reorganiza as carreiras funcionais dos guardas municipais e que trata do enquadramento do cargo de Guarda Municipal 1\u00aa Classe. A lei n\u00ba 5.134 disp\u00f5e sobre a reorganiza\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-11241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11241"}],"version-history":[{"count":1,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11241\/revisions"}],"predecessor-version":[{"id":11244,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11241\/revisions\/11244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media\/11243"}],"wp:attachment":[{"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acontecenafronteira.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}